{"id":14325,"date":"2025-12-11T22:46:23","date_gmt":"2025-12-11T21:46:23","guid":{"rendered":"https:\/\/okitalk.news\/de\/video\/9c461b\/automatisch-gespeicherter-entwurf\/"},"modified":"2026-06-28T19:01:42","modified_gmt":"2026-06-28T17:01:42","slug":"living-earth-projektwerkstatt-gehe-auf-ein-wanderjahr","status":"publish","type":"okitalk_video","link":"https:\/\/okitalk.news\/de\/video\/living-earth-projektwerkstatt-gehe-auf-ein-wanderjahr\/","title":{"rendered":"Living Earth &#8211; Projektwerkstatt &#8211; Gehe auf ein Wanderjahr"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Als ich (Catharina) vor ein paar Wochen beim Apfelbl\u00fctenfest beim Projekt Mirabergen auf Besuch war, fiel mir ein enthusiastischer junger Mann auf, der mir erz\u00e4hlte, dass er im Rahmen seines &#8222;WANDERJAHRES&#8220; in Mirabergen unterwegs ist und kurz davor bei Johannes Eisenbach in Kalamata (Griechenland) super interessante Dinge \u00fcber die zyklisch-vegane Humusveredelung gelernt hatte. Hendryk erz\u00e4hlt mir begeistert von den Erlebnissen des Wanderjahres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie der &#8222;Zu-fall&#8220; so will, sa\u00df ich vor ein paar Tagen in Griechenland beim Geburtstag unserer Weisenr\u00e4tin Vera Brandes neben Sabine Langer, der Mit-Gr\u00fcnderin von MENSCHLICH WIRTSCHAFTEN und Initiatorin des <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr\/\"><strong><u>WANDERJAHRES<\/u><\/strong><\/a><strong>.<\/strong><br>Schaue Dir gerne auch die <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr-2025-2026-in-bildern\/\"><strong><u>Bilder<\/u><\/strong><\/a> vom laufenden Wanderjahr an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und so laden wir Dich nun gemeinsam ein, das <strong>Konzept des Wanderjahres<\/strong> kennen zu lernen und vielleicht sogar selbst auf Wanderschaft zu gehen.<br>Schon ein paar Tage nach dieser Projektwerkstatt findet ein Zoom-Austausch statt, bei dem Du Dich vorstellen und dann pers\u00f6nlich weiter informieren kannst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ist das Wanderjahr etwas f\u00fcr Dich &#8211; was ist das Wanderjahr?<\/strong><br>Das solltest du wissen<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Wanderjahr dauert jeweils von <strong>Anfang September bis Ende Juli des Folgejahres<\/strong>.<br><strong>Du bist zwischen 18 und 25<\/strong> (unter bestimmten Bedingungen ist eine Aufnahme auch ab 16 Jahren m\u00f6glich) und bereit, Dich inneren Fragen zu \u00f6ffnen, 11 Monate Teil einer verbindlichen Gemeinschaft zu sein und an wechselnden Orten tatkr\u00e4ftig mit anzupacken?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dich erwarten <strong>4-8 w\u00f6chige Praxiseins\u00e4tze<\/strong> in unserem wachsenden Netzwerk: <strong>Landwirtschaft<\/strong>, <strong>Handwerk<\/strong>, <strong>Unternehmen<\/strong>, <strong>Gesundheitsinitiativen<\/strong> im In- und Ausland<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die zweite Jahresh\u00e4lfte kannst Du Dir auch selbst <strong>Einsatzorte nach Deinen Interessen<\/strong> suchen. Dazwischen trifft sich die Gruppe zu gemeinsamen <strong>Seminarwochen<\/strong>, in denen die gemachten Erfahrungen bewegt werden und verschiedene Dozenten zu Besuch kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein <strong>Theaterprojekt<\/strong> gibt k\u00fcnstlerischen Entfaltungsraum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zwei <strong>Mentoren<\/strong> begleiten Dich die ganze Zeit \u00fcber als verl\u00e4ssliche Ansprechpartner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In dieser Projektwerkstatt wird uns<br>Sabine Gl\u00e4ser<br>eine Gr\u00fcnderin von MENSCHLICH WIRTSCHAFTEN<br>\u00fcber das Wanderjahr erz\u00e4hlen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wir finden, dies ist eine wundervolle Chance f\u00fcr ein geniales Jahr,<\/strong><br><strong>viele Erfahrungen, viel neues Wissen und Vernetzung,<\/strong><br><strong>die ein Leben lang halten kann.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabine Gl\u00e4ser <strong><a href=\"https:\/\/menschlichwirtschaften.de\">menschlichwirtschaften.de<\/a><\/strong><br>kontakt@menschlichwirtschaften.de<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch die Sendung f\u00fchrt <strong>Catharina Roland von der LIVING EARTH<br><a href=\"https:\/\/www.livingearth.one\">www.livingearth.one<\/a><\/strong><br>pioniere@livingearth.one<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr zur Living Earth unter:<br><strong><a href=\"http:\/\/www.livingearth.one\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.livingearth.one<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als ich (Catharina) vor ein paar Wochen beim Apfelbl\u00fctenfest beim Projekt Mirabergen auf Besuch war, fiel mir ein enthusiastischer junger Mann auf, der mir erz\u00e4hlte, dass er im Rahmen seines &#8222;WANDERJAHRES&#8220; in Mirabergen unterwegs ist und kurz davor bei Johannes Eisenbach in Kalamata (Griechenland) super interessante Dinge \u00fcber die zyklisch-vegane Humusveredelung gelernt hatte. Hendryk erz\u00e4hlt [&hellip;]<\/p>\n","protected":false},"featured_media":16419,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","tags":[419,442,34],"okitalk_topic":[18,23,16],"okitalk_guest":[2242],"class_list":["post-14325","okitalk_video","type-okitalk_video","status-publish","has-post-thumbnail","hentry","tag-living-earth","tag-masterclass","tag-okitalk","okitalk_topic-community-social-justice","okitalk_topic-culture-identity-travel","okitalk_topic-okitalk-international","okitalk_guest-sabine-langer"],"meta":{"_en_post_content":"<!-- wp:paragraph -->\n<p>When I (Catharina) visited the apple blossom festival at the Mirabergen project a few weeks ago, I noticed an enthusiastic young man who told me that he is traveling in Mirabergen as part of his \"WANDER YEAR\" and had just learned super interesting things about cyclical-vegan humus refinement from Johannes Eisenbach in Kalamata (Greece). Hendryk enthusiastically tells me about the experiences of the wander year.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>As \"chance\" would have it, a few days ago I was in Greece sitting next to Sabine Langer, the co-founder of MENSCHLICH WIRTSCHAFTEN and initiator of the <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr\/\"><strong><u>WANDER YEAR<\/u><\/strong><\/a><strong>.<\/strong><br>Feel free to also check out the <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr-2025-2026-in-bildern\/\"><strong><u>pictures<\/u><\/strong><\/a> from the current wander year.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>And so we now invite you together to get to know the <strong>concept of the wander year<\/strong> and perhaps even go on a journey yourself.<br>A few days after this project workshop, a Zoom exchange will take place where you can introduce yourself and then get further information personally.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Is the wander year something for you - what is the wander year?<\/strong><br>You should know this<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>The wander year lasts from <strong>early September to the end of July of the following year<\/strong>.<br><strong>You are between 18 and 25<\/strong> (under certain conditions, admission is also possible from 16 years) and ready to open yourself to inner questions, to be part of a binding community for 11 months, and to actively help out at changing locations?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>You can expect <strong>4-8 week practical assignments<\/strong> in our growing network: <strong>agriculture<\/strong>, <strong>crafts<\/strong>, <strong>businesses<\/strong>, <strong>health initiatives<\/strong> in Germany and abroad.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>For the second half of the year, you can also <strong>choose assignment locations according to your interests<\/strong>. In between, the group meets for joint <strong>seminar weeks<\/strong>, where the experiences made are discussed and various lecturers come to visit.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>A <strong>theater project<\/strong> provides artistic space for development.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Two <strong>mentors<\/strong> accompany you the whole time as reliable contacts.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>In this project workshop, Sabine Gl\u00e4ser, a founder of MENSCHLICH WIRTSCHAFTEN, will tell us about the wander year.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>We believe this is a wonderful opportunity for a brilliant year,<\/strong><br><strong>many experiences, much new knowledge and networking,<\/strong><br><strong>that can last a lifetime.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sabine Gl\u00e4ser <strong><a href=\"https:\/\/menschlichwirtschaften.de\">menschlichwirtschaften.de<\/a><\/strong><br>kontakt@menschlichwirtschaften.de<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>The show is hosted by <strong>Catharina Roland from LIVING EARTH<br><a href=\"https:\/\/www.livingearth.one\">www.livingearth.one<\/a><\/strong><br>pioniere@livingearth.one<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>More about Living Earth at:<br><strong><a href=\"http:\/\/www.livingearth.one\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.livingearth.one<\/a><\/strong><\/p>\n<!-- \/wp:paragraph -->","_en_post_excerpt":"","_en_post_title":"Living Earth - Project Workshop - Go on a Hiking Year","_en_post_name":"","_de_post_content":"<!-- wp:paragraph -->\n<p>Als ich (Catharina) vor ein paar Wochen beim Apfelbl\u00fctenfest beim Projekt Mirabergen auf Besuch war, fiel mir ein enthusiastischer junger Mann auf, der mir erz\u00e4hlte, dass er im Rahmen seines \"WANDERJAHRES\" in Mirabergen unterwegs ist und kurz davor bei Johannes Eisenbach in Kalamata (Griechenland) super interessante Dinge \u00fcber die zyklisch-vegane Humusveredelung gelernt hatte. Hendryk erz\u00e4hlt mir begeistert von den Erlebnissen des Wanderjahres.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wie der \"Zu-fall\" so will, sa\u00df ich vor ein paar Tagen in Griechenland beim Geburtstag unserer Weisenr\u00e4tin Vera Brandes neben Sabine Langer, der Mit-Gr\u00fcnderin von MENSCHLICH WIRTSCHAFTEN und Initiatorin des <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr\/\"><strong><u>WANDERJAHRES<\/u><\/strong><\/a><strong>.<\/strong><br>Schaue Dir gerne auch die <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr-2025-2026-in-bildern\/\"><strong><u>Bilder<\/u><\/strong><\/a> vom laufenden Wanderjahr an.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Und so laden wir Dich nun gemeinsam ein, das <strong>Konzept des Wanderjahres<\/strong> kennen zu lernen und vielleicht sogar selbst auf Wanderschaft zu gehen.<br>Schon ein paar Tage nach dieser Projektwerkstatt findet ein Zoom-Austausch statt, bei dem Du Dich vorstellen und dann pers\u00f6nlich weiter informieren kannst.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Ist das Wanderjahr etwas f\u00fcr Dich - was ist das Wanderjahr?<\/strong><br>Das solltest du wissen<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Das Wanderjahr dauert jeweils von <strong>Anfang September bis Ende Juli des Folgejahres<\/strong>.<br><strong>Du bist zwischen 18 und 25<\/strong> (unter bestimmten Bedingungen ist eine Aufnahme auch ab 16 Jahren m\u00f6glich) und bereit, Dich inneren Fragen zu \u00f6ffnen, 11 Monate Teil einer verbindlichen Gemeinschaft zu sein und an wechselnden Orten tatkr\u00e4ftig mit anzupacken?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dich erwarten <strong>4-8 w\u00f6chige Praxiseins\u00e4tze<\/strong> in unserem wachsenden Netzwerk: <strong>Landwirtschaft<\/strong>, <strong>Handwerk<\/strong>, <strong>Unternehmen<\/strong>, <strong>Gesundheitsinitiativen<\/strong> im In- und Ausland<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>F\u00fcr die zweite Jahresh\u00e4lfte kannst Du Dir auch selbst <strong>Einsatzorte nach Deinen Interessen<\/strong> suchen. Dazwischen trifft sich die Gruppe zu gemeinsamen <strong>Seminarwochen<\/strong>, in denen die gemachten Erfahrungen bewegt werden und verschiedene Dozenten zu Besuch kommen.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Ein <strong>Theaterprojekt<\/strong> gibt k\u00fcnstlerischen Entfaltungsraum.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Zwei <strong>Mentoren<\/strong> begleiten Dich die ganze Zeit \u00fcber als verl\u00e4ssliche Ansprechpartner.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>In dieser Projektwerkstatt wird uns<br>Sabine Gl\u00e4ser<br>eine Gr\u00fcnderin von MENSCHLICH WIRTSCHAFTEN<br>\u00fcber das Wanderjahr erz\u00e4hlen.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Wir finden, dies ist eine wundervolle Chance f\u00fcr ein geniales Jahr,<\/strong><br><strong>viele Erfahrungen, viel neues Wissen und Vernetzung,<\/strong><br><strong>die ein Leben lang halten kann.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sabine Gl\u00e4ser <strong><a href=\"https:\/\/menschlichwirtschaften.de\">menschlichwirtschaften.de<\/a><\/strong><br>kontakt@menschlichwirtschaften.de<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Durch die Sendung f\u00fchrt <strong>Catharina Roland von der LIVING EARTH<br><a href=\"https:\/\/www.livingearth.one\">www.livingearth.one<\/a><\/strong><br>pioniere@livingearth.one<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Mehr zur Living Earth unter:<br><strong><a href=\"http:\/\/www.livingearth.one\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.livingearth.one<\/a><\/strong><\/p>\n<!-- \/wp:paragraph -->","_de_post_excerpt":"","_de_post_title":"Living Earth - Projektwerkstatt - Gehe auf ein Wanderjahr","_de_post_name":"living-earth-projektwerkstatt-gehe-auf-ein-wanderjahr","_es_post_content":"<!-- wp:paragraph -->\n<p>Cuando estuve (Catharina) hace unas semanas en el festival de flores de manzano del proyecto Mirabergen, me llam\u00f3 la atenci\u00f3n un joven entusiasta que me cont\u00f3 que estaba de viaje en Mirabergen como parte de su \"A\u00d1O DE VIAJE\" y que poco antes hab\u00eda aprendido cosas muy interesantes sobre la mejora c\u00edclica y vegana del humus con Johannes Eisenbach en Kalamata (Grecia). Hendryk me habla con entusiasmo sobre las experiencias del a\u00f1o de viaje.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Como el \"azar\" lo quiere, hace unos d\u00edas me sent\u00e9 en Grecia junto a Sabine Langer, la cofundadora de MENSCHLICH WIRTSCHAFTEN y la iniciadora del <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr\/\"><strong><u>A\u00d1O DE VIAJE<\/u><\/strong><\/a><strong>.<\/strong><br>Te invito a que tambi\u00e9n veas las <a href=\"https:\/\/menschlichwirtschaften.de\/wanderjahr-2025-2026-in-bildern\/\"><strong><u>im\u00e1genes<\/u><\/strong><\/a> del a\u00f1o de viaje en curso.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Y as\u00ed te invitamos juntos a conocer el <strong>concepto del a\u00f1o de viaje<\/strong> y quiz\u00e1s incluso a emprender tu propia traves\u00eda.<br>Pocos d\u00edas despu\u00e9s de este taller del proyecto, habr\u00e1 un intercambio por Zoom donde podr\u00e1s presentarte y luego informarte personalmente.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>\u00bfEs el a\u00f1o de viaje algo para ti - qu\u00e9 es el a\u00f1o de viaje?<\/strong><br>Esto es lo que deber\u00edas saber<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>El a\u00f1o de viaje dura desde <strong>principios de septiembre hasta finales de julio del a\u00f1o siguiente<\/strong>.<br><strong>Tienes entre 18 y 25 a\u00f1os<\/strong> (bajo ciertas condiciones, tambi\u00e9n es posible la admisi\u00f3n a partir de 16 a\u00f1os) y est\u00e1s dispuesto a abrirte a preguntas internas, ser parte de una comunidad vinculante durante 11 meses y trabajar activamente en lugares cambiantes?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Te esperan <strong>pr\u00e1cticas de 4 a 8 semanas<\/strong> en nuestra red en crecimiento: <strong>agricultura<\/strong>, <strong>artesan\u00eda<\/strong>, <strong>empresas<\/strong>, <strong>iniciativas de salud<\/strong> en el pa\u00eds y en el extranjero<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Para la segunda mitad del a\u00f1o, tambi\u00e9n puedes buscar <strong>lugares de trabajo seg\u00fan tus intereses<\/strong>. Entre tanto, el grupo se re\u00fane para <strong>semanas de seminario<\/strong> conjuntas, donde se discuten las experiencias adquiridas y varios docentes vienen de visita.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Un <strong>proyecto teatral<\/strong> ofrece espacio para la expresi\u00f3n art\u00edstica.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Dos <strong>mentores<\/strong> te acompa\u00f1an durante todo el tiempo como contactos confiables.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>En este taller del proyecto, nos<br>hablar\u00e1 Sabine Gl\u00e4ser,<br>una fundadora de MENSCHLICH WIRTSCHAFTEN,<br>sobre el a\u00f1o de viaje.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Creemos que esta es una maravillosa oportunidad para un a\u00f1o genial,<\/strong><br><strong>muchas experiencias, mucho nuevo conocimiento y conexi\u00f3n,<\/strong><br><strong>que puede durar toda la vida.<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Sabine Gl\u00e4ser <strong><a href=\"https:\/\/menschlichwirtschaften.de\">menschlichwirtschaften.de<\/a><\/strong><br>contact@menschlichwirtschaften.de<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>La transmisi\u00f3n es conducida por <strong>Catharina Roland de LIVING EARTH<br><a href=\"https:\/\/www.livingearth.one\">www.livingearth.one<\/a><\/strong><br>pioniere@livingearth.one<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>M\u00e1s sobre Living Earth en:<br><strong><a href=\"http:\/\/www.livingearth.one\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.livingearth.one<\/a><\/strong><\/p>\n<!-- \/wp:paragraph -->","_es_post_excerpt":"","_es_post_title":"Tierra Viva - Taller de Proyecto - Ve a un a\u00f1o de caminata","_es_post_name":"","edit_language":"de"},"_links":{"self":[{"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_video\/14325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_video"}],"about":[{"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/types\/okitalk_video"}],"replies":[{"embeddable":true,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/comments?post=14325"}],"version-history":[{"count":3,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_video\/14325\/revisions"}],"predecessor-version":[{"id":16948,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_video\/14325\/revisions\/16948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/media\/16419"}],"wp:attachment":[{"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/media?parent=14325"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/tags?post=14325"},{"taxonomy":"okitalk_topic","embeddable":true,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_topic?post=14325"},{"taxonomy":"okitalk_guest","embeddable":true,"href":"https:\/\/okitalk.news\/de\/wp-json\/wp\/v2\/okitalk_guest?post=14325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}